{"id":17021,"date":"2021-12-01T00:30:54","date_gmt":"2021-12-01T00:30:54","guid":{"rendered":"https:\/\/woodriverweekly.com\/?p=17021"},"modified":"2021-11-30T18:38:32","modified_gmt":"2021-11-30T18:38:32","slug":"estamos-escuchando","status":"publish","type":"post","link":"https:\/\/woodriverweekly.com\/index.php\/2021\/12\/01\/estamos-escuchando\/","title":{"rendered":"Estamos Escuchando!"},"content":{"rendered":"<p class=\"p1\"><em>POR KAREN SHARPNACK, DIRECTORA EJECUTIVA<\/em><\/p>\n<p class=\"p3\"><b>NUESTRA VOZ CUENTA<\/b><\/p>\n<p class=\"p4\">La Coalici\u00f3n de Inmunizaci\u00f3n de Idaho, una organizaci\u00f3n estatal sin fines de lucro, ha estado pasando por la parte sur de Idaho y ha querido entender por qu\u00e9 los latinos no est\u00e1n accediendo a la vacuna COVID-19 en comparaci\u00f3n con otros grupos \u00e9tnicos y raciales. Al 8 de noviembre de 2021, seg\u00fan el recuento de casos entre hispanos est\u00e1 mejorando, pero la tasa de vacunaci\u00f3n entre hispanos es m\u00e1s baja que la tasa estatal. La tasa de vacunaci\u00f3n contra el COVID-19 para los hispanos en Idaho es del 37%, seg\u00fan datos del Departamento de Salud y Bienestar de Idaho.<\/p>\n<p class=\"p6\">\u00bfC\u00f3mo lleva a cabo la Coalici\u00f3n de Inmunizaci\u00f3n de Idaho una sesi\u00f3n de escucha? La Coordinadora de Equidad en Salud de la Coalici\u00f3n de Inmunizaci\u00f3n de Idaho, Kim Guevara, identifica a un l\u00edder comunitario para ayudar a reunir a un grupo de 8 a 10 personas en persona a un restaurante, establecimiento de caf\u00e9 o negocio local para escuchar sus preocupaciones sobre el acceso a la vacuna COVID-19, por qu\u00e9 es posible que no hayan tomado la vacuna y sugerencias para ayudarnos a comunicarnos de manera m\u00e1s efectiva sobre la vacuna.<\/p>\n<p class=\"p6\">\u00bfQu\u00e9 hace la Coalici\u00f3n de Inmunizaci\u00f3n de Idaho con la informaci\u00f3n que se comparti\u00f3 en la sesi\u00f3n de escucha? Reunimos los comentarios escuchados e identificamos los 2 a 3 mejores y trabajamos en c\u00f3mo podemos mejorar nuestras cl\u00ednicas de vacunaci\u00f3n para las comunidades Latinas, fortalecer nuestras estrategias de marketing y compartir los resultados con organizaciones de ideas afines para que puedan mejorar la forma en que llevan a cabo sus cl\u00ednicas.<\/p>\n<p class=\"p6\">Para obtener m\u00e1s informaci\u00f3n sobre la Coalici\u00f3n de Inmunizaci\u00f3n de Idaho: www.getimmunizedidaho.org o comun\u00edquese con Kim Guevara al (208) 504-6195.<\/p>\n<p><img loading=\"lazy\" decoding=\"async\" class=\"size-medium wp-image-12762 aligncenter\" src=\"https:\/\/woodriverweekly.com\/wp-content\/uploads\/2020\/01\/burgundy-projectoolsuccess-1-300x71.png\" alt=\"NUESTRA VOZ CUENTA\" width=\"300\" height=\"71\" \/><\/p>\n","protected":false},"excerpt":{"rendered":"<p>POR KAREN SHARPNACK, DIRECTORA EJECUTIVA NUESTRA VOZ CUENTA La Coalici\u00f3n de Inmunizaci\u00f3n de Idaho, una organizaci\u00f3n estatal sin fines de lucro, ha estado pasando por la parte sur de Idaho y ha querido entender por qu\u00e9 los latinos no est\u00e1n accediendo a la vacuna COVID-19 en comparaci\u00f3n con otros grupos \u00e9tnicos y raciales. Al 8 [&hellip;]<\/p>\n","protected":false},"author":1,"featured_media":17022,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"tdm_status":"","tdm_grid_status":"","_pvb_checkbox_block_on_post":false,"footnotes":""},"categories":[93,38],"tags":[],"class_list":{"0":"post-17021","1":"post","2":"type-post","3":"status-publish","4":"format-standard","5":"has-post-thumbnail","7":"category-nuestra-voz-cuenta","8":"category-sponsored"},"_links":{"self":[{"href":"https:\/\/woodriverweekly.com\/index.php\/wp-json\/wp\/v2\/posts\/17021","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/woodriverweekly.com\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/woodriverweekly.com\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/woodriverweekly.com\/index.php\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/woodriverweekly.com\/index.php\/wp-json\/wp\/v2\/comments?post=17021"}],"version-history":[{"count":1,"href":"https:\/\/woodriverweekly.com\/index.php\/wp-json\/wp\/v2\/posts\/17021\/revisions"}],"predecessor-version":[{"id":17023,"href":"https:\/\/woodriverweekly.com\/index.php\/wp-json\/wp\/v2\/posts\/17021\/revisions\/17023"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/woodriverweekly.com\/index.php\/wp-json\/wp\/v2\/media\/17022"}],"wp:attachment":[{"href":"https:\/\/woodriverweekly.com\/index.php\/wp-json\/wp\/v2\/media?parent=17021"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/woodriverweekly.com\/index.php\/wp-json\/wp\/v2\/categories?post=17021"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/woodriverweekly.com\/index.php\/wp-json\/wp\/v2\/tags?post=17021"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}